{"id":4551,"date":"2025-11-24T14:51:00","date_gmt":"2025-11-24T12:51:00","guid":{"rendered":"https:\/\/ajmonnet.eu\/?post_type=events&#038;p=4551"},"modified":"2025-12-01T14:55:40","modified_gmt":"2025-12-01T12:55:40","slug":"quelle-defense-pour-leurope","status":"publish","type":"events","link":"https:\/\/ajmonnet.eu\/it\/events\/quelle-defense-pour-leurope\/","title":{"rendered":"Quale difesa per l'Europa?"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-24-at-17.57.46-819x1024.jpeg\" alt=\"\" class=\"wp-image-4552\" srcset=\"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-24-at-17.57.46-819x1024.jpeg 819w, https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-24-at-17.57.46-240x300.jpeg 240w, https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-24-at-17.57.46-768x960.jpeg 768w, https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-24-at-17.57.46-10x12.jpeg 10w, https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-24-at-17.57.46.jpeg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>","protected":false},"featured_media":4552,"template":"","categories":[31],"class_list":["post-4551","events","type-events","status-publish","has-post-thumbnail","hentry","category-actualite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quelle d\u00e9fense pour l&#039;Europe<\/title>\n<meta name=\"description\" content=\"Association Jean Monnet - Think tank Europ\u00e9en, l&#039;association Jean Monnet propose r\u00e9guli\u00e8rement des \u00e9v\u00e8nements sur l&#039;actualit\u00e9 europ\u00e9enne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ajmonnet.eu\/it\/events\/quelle-defense-pour-leurope\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quelle d\u00e9fense pour l&#039;Europe\" \/>\n<meta property=\"og:description\" content=\"Association Jean Monnet - Think tank Europ\u00e9en, l&#039;association Jean Monnet propose r\u00e9guli\u00e8rement des \u00e9v\u00e8nements sur l&#039;actualit\u00e9 europ\u00e9enne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ajmonnet.eu\/it\/events\/quelle-defense-pour-leurope\/\" \/>\n<meta property=\"og:site_name\" content=\"Association Jean Monnet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/associationjeanmonnet\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T12:55:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-24-at-17.57.46.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AJMonnet\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/quelle-defense-pour-leurope\\\/\",\"url\":\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/quelle-defense-pour-leurope\\\/\",\"name\":\"Quelle d\u00e9fense pour l'Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/quelle-defense-pour-leurope\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/quelle-defense-pour-leurope\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ajmonnet.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-11-24-at-17.57.46.jpeg\",\"datePublished\":\"2025-11-24T12:51:00+00:00\",\"dateModified\":\"2025-12-01T12:55:40+00:00\",\"description\":\"Association Jean Monnet - Think tank Europ\u00e9en, l'association Jean Monnet propose r\u00e9guli\u00e8rement des \u00e9v\u00e8nements sur l'actualit\u00e9 europ\u00e9enne.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/quelle-defense-pour-leurope\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/quelle-defense-pour-leurope\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/quelle-defense-pour-leurope\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ajmonnet.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-11-24-at-17.57.46.jpeg\",\"contentUrl\":\"https:\\\/\\\/ajmonnet.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-11-24-at-17.57.46.jpeg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/quelle-defense-pour-leurope\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ajmonnet.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"http:\\\/\\\/ajmonnet.eu\\\/pl\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quelle d\u00e9fense pour l&rsquo;Europe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/#website\",\"url\":\"https:\\\/\\\/ajmonnet.eu\\\/\",\"name\":\"Association Jean Monnet\",\"description\":\"Faire vivre au temps pr\u00e9sent les id\u00e9es europ\u00e9ennes de Jean Monnet\",\"publisher\":{\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/#organization\"},\"alternateName\":\"AJM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ajmonnet.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/#organization\",\"name\":\"ASSOCIATION JEAN MONNET\",\"alternateName\":\"AJM\",\"url\":\"https:\\\/\\\/ajmonnet.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ajmonnet.eu\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/AJM-Logo-Color.png\",\"contentUrl\":\"https:\\\/\\\/ajmonnet.eu\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/AJM-Logo-Color.png\",\"width\":386,\"height\":241,\"caption\":\"ASSOCIATION JEAN MONNET\"},\"image\":{\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/associationjeanmonnet\",\"https:\\\/\\\/x.com\\\/AJMonnet\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/association-jean-monnet\",\"https:\\\/\\\/bsky.app\\\/profile\\\/ajeanmonnet.bsky.social\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Difesa per l'Europa","description":"Associazione Jean Monnet - Gruppo di riflessione europeo, l'Associazione Jean Monnet organizza regolarmente eventi sull'attualit\u00e0 europea.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ajmonnet.eu\/it\/events\/quelle-defense-pour-leurope\/","og_locale":"it_IT","og_type":"article","og_title":"Quelle d\u00e9fense pour l'Europe","og_description":"Association Jean Monnet - Think tank Europ\u00e9en, l'association Jean Monnet propose r\u00e9guli\u00e8rement des \u00e9v\u00e8nements sur l'actualit\u00e9 europ\u00e9enne.","og_url":"https:\/\/ajmonnet.eu\/it\/events\/quelle-defense-pour-leurope\/","og_site_name":"Association Jean Monnet","article_publisher":"https:\/\/www.facebook.com\/associationjeanmonnet","article_modified_time":"2025-12-01T12:55:40+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-24-at-17.57.46.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AJMonnet","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ajmonnet.eu\/events\/quelle-defense-pour-leurope\/","url":"https:\/\/ajmonnet.eu\/events\/quelle-defense-pour-leurope\/","name":"Difesa per l'Europa","isPartOf":{"@id":"https:\/\/ajmonnet.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ajmonnet.eu\/events\/quelle-defense-pour-leurope\/#primaryimage"},"image":{"@id":"https:\/\/ajmonnet.eu\/events\/quelle-defense-pour-leurope\/#primaryimage"},"thumbnailUrl":"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-24-at-17.57.46.jpeg","datePublished":"2025-11-24T12:51:00+00:00","dateModified":"2025-12-01T12:55:40+00:00","description":"Associazione Jean Monnet - Gruppo di riflessione europeo, l'Associazione Jean Monnet organizza regolarmente eventi sull'attualit\u00e0 europea.","breadcrumb":{"@id":"https:\/\/ajmonnet.eu\/events\/quelle-defense-pour-leurope\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ajmonnet.eu\/events\/quelle-defense-pour-leurope\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ajmonnet.eu\/events\/quelle-defense-pour-leurope\/#primaryimage","url":"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-24-at-17.57.46.jpeg","contentUrl":"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-24-at-17.57.46.jpeg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/ajmonnet.eu\/events\/quelle-defense-pour-leurope\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ajmonnet.eu\/"},{"@type":"ListItem","position":2,"name":"Events","item":"http:\/\/ajmonnet.eu\/pl\/events\/"},{"@type":"ListItem","position":3,"name":"Quelle d\u00e9fense pour l&rsquo;Europe"}]},{"@type":"WebSite","@id":"https:\/\/ajmonnet.eu\/#website","url":"https:\/\/ajmonnet.eu\/","name":"Associazione Jean Monnet","description":"Far rivivere le idee europee di Jean Monnet nel presente","publisher":{"@id":"https:\/\/ajmonnet.eu\/#organization"},"alternateName":"AJM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ajmonnet.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ajmonnet.eu\/#organization","name":"ASSOCIAZIONE JEAN MONNET","alternateName":"AJM","url":"https:\/\/ajmonnet.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ajmonnet.eu\/#\/schema\/logo\/image\/","url":"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2022\/04\/AJM-Logo-Color.png","contentUrl":"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2022\/04\/AJM-Logo-Color.png","width":386,"height":241,"caption":"ASSOCIATION JEAN MONNET"},"image":{"@id":"https:\/\/ajmonnet.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/associationjeanmonnet","https:\/\/x.com\/AJMonnet","https:\/\/www.linkedin.com\/company\/association-jean-monnet","https:\/\/bsky.app\/profile\/ajeanmonnet.bsky.social"]}]}},"_links":{"self":[{"href":"https:\/\/ajmonnet.eu\/it\/wp-json\/wp\/v2\/events\/4551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ajmonnet.eu\/it\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/ajmonnet.eu\/it\/wp-json\/wp\/v2\/types\/events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajmonnet.eu\/it\/wp-json\/wp\/v2\/media\/4552"}],"wp:attachment":[{"href":"https:\/\/ajmonnet.eu\/it\/wp-json\/wp\/v2\/media?parent=4551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajmonnet.eu\/it\/wp-json\/wp\/v2\/categories?post=4551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}