{"id":4553,"date":"2025-11-24T14:56:00","date_gmt":"2025-11-24T12:56:00","guid":{"rendered":"https:\/\/ajmonnet.eu\/?post_type=events&#038;p=4553"},"modified":"2025-12-01T15:01:04","modified_gmt":"2025-12-01T13:01:04","slug":"la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales","status":"publish","type":"events","link":"https:\/\/ajmonnet.eu\/de\/events\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\/","title":{"rendered":"Der Krieg in der Ukraine und seine europ\u00e4ischen und internationalen Folgen"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Olivier V\u00e9drine wird vor den Studierenden der Universit\u00e4t Lausanne sprechen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Konferenz, die mit Unterst\u00fctzung der Jean-Monnet-Stiftung f\u00fcr Europa durchgef\u00fchrt wurde.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-22-at-11.46.25-1024x1024.jpeg\" alt=\"\" class=\"wp-image-4554\" srcset=\"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-22-at-11.46.25-1024x1024.jpeg 1024w, https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-22-at-11.46.25-300x300.jpeg 300w, https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-22-at-11.46.25-150x150.jpeg 150w, https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-22-at-11.46.25-768x768.jpeg 768w, https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-22-at-11.46.25-12x12.jpeg 12w, https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-22-at-11.46.25.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"featured_media":4554,"template":"","categories":[31,3],"class_list":["post-4553","events","type-events","status-publish","has-post-thumbnail","hentry","category-actualite","category-ukraine"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La guerre d&#039;Ukraine et ses cons\u00e9quences europ\u00e9ennes et internationales<\/title>\n<meta name=\"description\" content=\"Association Jean Monnet - Think tank Europ\u00e9en, l&#039;association Jean Monnet propose r\u00e9guli\u00e8rement des \u00e9v\u00e8nements sur l&#039;actualit\u00e9 europ\u00e9enne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ajmonnet.eu\/de\/events\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La guerre d&#039;Ukraine et ses cons\u00e9quences europ\u00e9ennes et internationales\" \/>\n<meta property=\"og:description\" content=\"Association Jean Monnet - Think tank Europ\u00e9en, l&#039;association Jean Monnet propose r\u00e9guli\u00e8rement des \u00e9v\u00e8nements sur l&#039;actualit\u00e9 europ\u00e9enne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ajmonnet.eu\/de\/events\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\/\" \/>\n<meta property=\"og:site_name\" content=\"Association Jean Monnet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/associationjeanmonnet\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T13:01:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-22-at-11.46.25.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AJMonnet\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\\\/\",\"url\":\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\\\/\",\"name\":\"La guerre d'Ukraine et ses cons\u00e9quences europ\u00e9ennes et internationales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ajmonnet.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-11-22-at-11.46.25.jpeg\",\"datePublished\":\"2025-11-24T12:56:00+00:00\",\"dateModified\":\"2025-12-01T13:01:04+00:00\",\"description\":\"Association Jean Monnet - Think tank Europ\u00e9en, l'association Jean Monnet propose r\u00e9guli\u00e8rement des \u00e9v\u00e8nements sur l'actualit\u00e9 europ\u00e9enne.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ajmonnet.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-11-22-at-11.46.25.jpeg\",\"contentUrl\":\"https:\\\/\\\/ajmonnet.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-11-22-at-11.46.25.jpeg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/events\\\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ajmonnet.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"http:\\\/\\\/ajmonnet.eu\\\/pl\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La guerre d&rsquo;Ukraine et ses cons\u00e9quences europ\u00e9ennes et internationales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/#website\",\"url\":\"https:\\\/\\\/ajmonnet.eu\\\/\",\"name\":\"Association Jean Monnet\",\"description\":\"Faire vivre au temps pr\u00e9sent les id\u00e9es europ\u00e9ennes de Jean Monnet\",\"publisher\":{\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/#organization\"},\"alternateName\":\"AJM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ajmonnet.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/#organization\",\"name\":\"ASSOCIATION JEAN MONNET\",\"alternateName\":\"AJM\",\"url\":\"https:\\\/\\\/ajmonnet.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ajmonnet.eu\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/AJM-Logo-Color.png\",\"contentUrl\":\"https:\\\/\\\/ajmonnet.eu\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/AJM-Logo-Color.png\",\"width\":386,\"height\":241,\"caption\":\"ASSOCIATION JEAN MONNET\"},\"image\":{\"@id\":\"https:\\\/\\\/ajmonnet.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/associationjeanmonnet\",\"https:\\\/\\\/x.com\\\/AJMonnet\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/association-jean-monnet\",\"https:\\\/\\\/bsky.app\\\/profile\\\/ajeanmonnet.bsky.social\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Krieg in der Ukraine und seine europ\u00e4ischen und internationalen Folgen","description":"Association Jean Monnet - Der europ\u00e4ische Think Tank, die Association Jean Monnet, bietet regelm\u00e4\u00dfig Veranstaltungen zu aktuellen europ\u00e4ischen Themen an.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ajmonnet.eu\/de\/events\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\/","og_locale":"de_DE","og_type":"article","og_title":"La guerre d'Ukraine et ses cons\u00e9quences europ\u00e9ennes et internationales","og_description":"Association Jean Monnet - Think tank Europ\u00e9en, l'association Jean Monnet propose r\u00e9guli\u00e8rement des \u00e9v\u00e8nements sur l'actualit\u00e9 europ\u00e9enne.","og_url":"https:\/\/ajmonnet.eu\/de\/events\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\/","og_site_name":"Association Jean Monnet","article_publisher":"https:\/\/www.facebook.com\/associationjeanmonnet","article_modified_time":"2025-12-01T13:01:04+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-22-at-11.46.25.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AJMonnet","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ajmonnet.eu\/events\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\/","url":"https:\/\/ajmonnet.eu\/events\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\/","name":"Der Krieg in der Ukraine und seine europ\u00e4ischen und internationalen Folgen","isPartOf":{"@id":"https:\/\/ajmonnet.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ajmonnet.eu\/events\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\/#primaryimage"},"image":{"@id":"https:\/\/ajmonnet.eu\/events\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\/#primaryimage"},"thumbnailUrl":"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-22-at-11.46.25.jpeg","datePublished":"2025-11-24T12:56:00+00:00","dateModified":"2025-12-01T13:01:04+00:00","description":"Association Jean Monnet - Der europ\u00e4ische Think Tank, die Association Jean Monnet, bietet regelm\u00e4\u00dfig Veranstaltungen zu aktuellen europ\u00e4ischen Themen an.","breadcrumb":{"@id":"https:\/\/ajmonnet.eu\/events\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ajmonnet.eu\/events\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ajmonnet.eu\/events\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\/#primaryimage","url":"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-22-at-11.46.25.jpeg","contentUrl":"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-11-22-at-11.46.25.jpeg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/ajmonnet.eu\/events\/la-guerre-dukraine-et-ses-consequences-europeennes-et-internationales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ajmonnet.eu\/"},{"@type":"ListItem","position":2,"name":"Events","item":"http:\/\/ajmonnet.eu\/pl\/events\/"},{"@type":"ListItem","position":3,"name":"La guerre d&rsquo;Ukraine et ses cons\u00e9quences europ\u00e9ennes et internationales"}]},{"@type":"WebSite","@id":"https:\/\/ajmonnet.eu\/#website","url":"https:\/\/ajmonnet.eu\/","name":"Jean-Monnet-Vereinigung","description":"Die europ\u00e4ischen Ideen von Jean Monnet in der heutigen Zeit weiterleben lassen","publisher":{"@id":"https:\/\/ajmonnet.eu\/#organization"},"alternateName":"AJM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ajmonnet.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ajmonnet.eu\/#organization","name":"VEREIN JEAN MONNET","alternateName":"AJM","url":"https:\/\/ajmonnet.eu\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ajmonnet.eu\/#\/schema\/logo\/image\/","url":"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2022\/04\/AJM-Logo-Color.png","contentUrl":"https:\/\/ajmonnet.eu\/wp-content\/uploads\/2022\/04\/AJM-Logo-Color.png","width":386,"height":241,"caption":"ASSOCIATION JEAN MONNET"},"image":{"@id":"https:\/\/ajmonnet.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/associationjeanmonnet","https:\/\/x.com\/AJMonnet","https:\/\/www.linkedin.com\/company\/association-jean-monnet","https:\/\/bsky.app\/profile\/ajeanmonnet.bsky.social"]}]}},"_links":{"self":[{"href":"https:\/\/ajmonnet.eu\/de\/wp-json\/wp\/v2\/events\/4553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ajmonnet.eu\/de\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/ajmonnet.eu\/de\/wp-json\/wp\/v2\/types\/events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajmonnet.eu\/de\/wp-json\/wp\/v2\/media\/4554"}],"wp:attachment":[{"href":"https:\/\/ajmonnet.eu\/de\/wp-json\/wp\/v2\/media?parent=4553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajmonnet.eu\/de\/wp-json\/wp\/v2\/categories?post=4553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}